{"id":5391,"date":"2026-04-17T12:55:45","date_gmt":"2026-04-17T17:55:45","guid":{"rendered":"https:\/\/www.emtrafesa.pe\/portal\/?page_id=5391"},"modified":"2026-06-03T15:23:32","modified_gmt":"2026-06-03T20:23:32","slug":"politica-privacidad-app-tracking","status":"publish","type":"page","link":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/politica-privacidad-app-tracking\/","title":{"rendered":"Pol\u00edtica de Privacidad &#8211; App Tracking"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5391\" class=\"elementor elementor-5391\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77e8611 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"77e8611\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2e9500\" data-id=\"a2e9500\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9922ac9 elementor-widget elementor-widget-shortcode\" data-id=\"9922ac9\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"metaslider-id-625\" style=\"width: 100%;\" class=\"ml-slider-3-25-1 metaslider metaslider-flex metaslider-625 ml-slider\">\n    <div id=\"metaslider_container_625\">\n        <div id=\"metaslider_625\" class=\"flexslider\">\n            <ul aria-live=\"polite\" class=\"slides\">\n                <li style=\"display: block; width: 100%;\" class=\"slide-5535 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/1.ANIVERSARIO.jpg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-5535\" title=\"1.ANIVERSARIO\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4546 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2023\/06\/slider-3.png\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-4546\" title=\"slider-3\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5536 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/2.-CAMA-180.jpg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-5536\" title=\"2. CAMA 180\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-4544 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/3.-TRUJILLO-CHICLAYO.jpg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-4544\" title=\"3. TRUJILLO CHICLAYO\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5537 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/4.TRUJILLO-LIMA.jpeg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-5537\" title=\"4.TRUJILLO LIMA\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5538 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/5.TRUJILLO-CAJAMARCA.jpeg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-5538\" title=\"5.TRUJILLO CAJAMARCA\" \/><\/li>\n                <li style=\"display: none; width: 100%;\" class=\"slide-5539 ms-image\"><img loading=\"lazy\" src=\"https:\/\/www.emtrafesa.pe\/portal\/wp-content\/uploads\/2026\/07\/6.CARGO-Y-ENCOMIENDA.jpeg\" height=\"600\" width=\"1800\" alt=\"\" class=\"slider-625 slide-5539\" title=\"6.CARGO Y ENCOMIENDA\" \/><\/li>\n            <\/ul>\n        <\/div>\n        \n    <\/div>\n<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d860f3f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d860f3f\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8bc918a\" data-id=\"8bc918a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e4478fa elementor-widget elementor-widget-heading\" data-id=\"3e4478fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Pol\u00edtica de Privacidad - App Tracking Emtrafesa<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556bf719 elementor-widget elementor-widget-text-editor\" data-id=\"556bf719\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<h3 style=\"text-align: justify;\"><span style=\"color: #333333; font-style: inherit;\"><b>1. Introducci\u00f3n<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">La presente Pol\u00edtica de Privacidad establece los t\u00e9rminos en que Emtrafesa usa y protege la informaci\u00f3n que es proporcionada por sus usuarios al momento de utilizar la aplicaci\u00f3n m\u00f3vil Tracking Emtrafesa (com.emtrafesa.tracking_app). Estamos comprometidos con la seguridad de los datos de nuestros usuarios de acuerdo con la Ley N\u00b0 29733 \u2013 Ley de Protecci\u00f3n de Datos Personales en Per\u00fa.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b style=\"color: #333333; font-style: inherit;\">2. Alcance<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333; font-style: inherit; font-weight: inherit;\">Esta pol\u00edtica se aplica exclusivamente al tratamiento de datos realizado a trav\u00e9s de la aplicaci\u00f3n m\u00f3vil mencionada. Al utilizar esta aplicaci\u00f3n, usted acepta las pr\u00e1cticas descritas en este documento.<br><\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>3. Recopilaci\u00f3n de Informaci\u00f3n y Transparencia<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Nuestra aplicaci\u00f3n m\u00f3vil ha sido dise\u00f1ada como una herramienta de consulta t\u00e9cnica. Bajo el principio de minimizaci\u00f3n de datos:&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><font color=\"#333333\">Datos que NO se recopilan: La aplicaci\u00f3n no accede, recopila ni almacena informaci\u00f3n sensible como ubicaci\u00f3n por GPS, lista de contactos, archivos multimedia, micr\u00f3fono o identificadores persistentes de publicidad<\/font><span style=\"color: #333333; font-style: inherit; font-weight: inherit;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><font color=\"#333333\"><span style=\"font-style: inherit; font-weight: inherit;\">Datos procesados para la consulta: Para el funcionamiento del servicio, el usuario ingresa de forma manual los datos del comprobante (Serie y Correlativo). Estos datos se procesan en tiempo real \u00fanicamente para realizar la petici\u00f3n al servidor.<\/span><\/font><br><br><font color=\"#333333\">Uso de la C\u00e1mara (Lector QR): La aplicaci\u00f3n solicita acceso a la c\u00e1mara del dispositivo con el \u00fanico fin de escanear los c\u00f3digos QR impresos en los comprobantes para autocompletar la serie y el correlativo de b\u00fasqueda. El procesamiento del c\u00f3digo QR ocurre enteramente en tiempo real dentro del dispositivo (localmente). La aplicaci\u00f3n no toma fotograf\u00edas, no graba videos, ni transmite, recopila o almacena im\u00e1genes de ning\u00fan tipo en nuestros servidores ni con terceros.<\/font><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>4. Uso de la Informaci\u00f3n<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">La informaci\u00f3n del comprobante proporcionada por el usuario se utiliza estrictamente para:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Consultar el estado actual del env\u00edo o encomienda en los sistemas de Emtrafesa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Mostrar al usuario la trazabilidad de su servicio.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Todas las comunicaciones entre la aplicaci\u00f3n y nuestros servidores se realizan a trav\u00e9s de conexiones seguras mediante el protocolo HTTPS, garantizando el cifrado de la informaci\u00f3n en tr\u00e1nsito.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>5. Proveedores de Servicios y Terceros<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Tracking Emtrafesa no comparte, vende ni cede la informaci\u00f3n procesada a terceros. La aplicaci\u00f3n no integra servicios de anal\u00edtica de comportamiento ni redes de publicidad que realicen rastreo de usuarios.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>6. Control del Usuario y Eliminaci\u00f3n de Datos<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Debido a que la aplicaci\u00f3n funciona bajo una modalidad de consulta directa y no requiere la creaci\u00f3n de una cuenta de usuario ni el registro de perfiles, no almacenamos datos personales en bases de datos persistentes a trav\u00e9s de la app. Por lo tanto, no existe informaci\u00f3n personal remanente que deba ser eliminada manualmente por el usuario.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>7. Permisos de la Aplicaci\u00f3n<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Para su correcto funcionamiento, la aplicaci\u00f3n solicita los siguientes permisos m\u00ednimos en Android:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">INTERNET: Necesario para conectar con el sistema de rastreo de encomiendas de Emtrafesa.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: rgb(51, 51, 51); font-style: inherit; font-weight: inherit;\">C\u00c1MARA: Requerido de forma opcional exclusivamente para habilitar la lectura r\u00e1pida de c\u00f3digos QR de los comprobantes.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>8. Cumplimiento Legal (Ley N\u00b0 29733)<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #333333;\">Emtrafesa garantiza que el tratamiento de cualquier dato se realiza respetando los principios de legalidad, consentimiento, finalidad y seguridad previstos en la normativa peruana de protecci\u00f3n de datos personales.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #333333;\"><b>9. Contacto de Soporte<\/b><\/span><\/h3>\n<p style=\"text-align: justify;\"><font color=\"#333333\">Si tiene alguna duda o pregunta sobre esta Pol\u00edtica de Privacidad o el funcionamiento de la aplicaci\u00f3n, puede ponerse en contacto con nuestro equipo t\u00e9cnico:<\/font><br><font color=\"#333333\">Empresa de Transportes Emtrafesa S.A.C. Av. T\u00fapac Amaru 185, Urb. Huerta Grande, Trujillo \u2013 Per\u00fa Tel\u00e9fono: (044) 484120<\/font><\/p>\n<p style=\"text-align: justify;\">\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-830411e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"830411e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-455d1a7\" data-id=\"455d1a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf5ec01 elementor-widget elementor-widget-html\" data-id=\"cf5ec01\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sticky-container colored-icons\" id=\"barraLateral\">\r\n    <ul class=\"sticky\">\r\n        <li>\r\n            <a href=\"https:\/\/api.whatsapp.com\/send?phone=949855871\" data-toggle=\"tooltip\" data-placement=\"left\" title=\"Realiza tu compra Online\" target=\"_blank\">\r\n                <i class=\"link-facebook fa fa-whatsapp \" style=\"font-size:53px;margin-left: 2px;padding-top: 10px;padding-left: 5px;\"><\/i><p style=\"text-align:center;\">\u00bfTe podemos <br>ayudar?<\/p>\r\n            <\/a>\r\n        <\/li>\r\n    <\/ul>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de Privacidad &#8211; App Tracking Emtrafesa 1. Introducci\u00f3n La presente Pol\u00edtica de Privacidad establece los t\u00e9rminos en que Emtrafesa usa y protege la informaci\u00f3n que es proporcionada por sus usuarios al momento de utilizar la aplicaci\u00f3n m\u00f3vil Tracking Emtrafesa (com.emtrafesa.tracking_app). Estamos comprometidos con la seguridad de los datos de nuestros usuarios de acuerdo con<a class=\"read-more\" href=\"https:\/\/www.emtrafesa.pe\/portal\/index.php\/politica-privacidad-app-tracking\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":[],"_links":{"self":[{"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/pages\/5391"}],"collection":[{"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/comments?post=5391"}],"version-history":[{"count":15,"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/pages\/5391\/revisions"}],"predecessor-version":[{"id":5450,"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/pages\/5391\/revisions\/5450"}],"wp:attachment":[{"href":"https:\/\/www.emtrafesa.pe\/portal\/index.php\/wp-json\/wp\/v2\/media?parent=5391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}